{"id":3286,"date":"2024-08-19T11:20:19","date_gmt":"2024-08-19T09:20:19","guid":{"rendered":"https:\/\/mallorcagolfholidays.com\/gdpr\/"},"modified":"2025-11-07T12:08:19","modified_gmt":"2025-11-07T11:08:19","slug":"dsvgo","status":"publish","type":"page","link":"https:\/\/mallorcagolfholidays.com\/de\/dsvgo\/","title":{"rendered":"DSVGO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3286\" class=\"elementor elementor-3286 elementor-2091\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a45edc3 e-con-full e-flex e-con e-parent\" data-id=\"a45edc3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5a6392 elementor-widget elementor-widget-template\" data-id=\"e5a6392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<header data-elementor-type=\"header\" data-elementor-id=\"3271\" class=\"elementor elementor-3271 elementor-545 elementor-545\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-8a0d06c e-con-full e-flex e-con e-child\" data-id=\"8a0d06c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-69780ee e-con-full e-flex e-con e-child\" data-id=\"69780ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f76c042 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"f76c042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/de\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"312\" height=\"87\" src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png\" class=\"attachment-medium_large size-medium_large wp-image-3071\" alt=\"\" srcset=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png 312w, https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent-300x84.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8594123 e-con-full e-flex e-con e-child\" data-id=\"8594123\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div data-dce-background-color=\"#FFFFFF00\" class=\"elementor-element elementor-element-8f9797f elementor-widget elementor-widget-button\" data-id=\"8f9797f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mallorcagolfholidays.com\/de\/schnelle-anfrage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SCHNELLE ANFRAGE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44e1669 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"44e1669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Doff_canvas%3Atoggle%26settings%3DeyJpZCI6ImQzZDRhMzkiLCJkaXNwbGF5TW9kZSI6InRvZ2dsZSJ9\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bars\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M16 132h416c8.837 0 16-7.163 16-16V76c0-8.837-7.163-16-16-16H16C7.163 60 0 67.163 0 76v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-302e461 e-flex e-con-boxed e-con e-parent\" data-id=\"302e461\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-background-color=\"#FFFFFF\" class=\"elementor-element elementor-element-d3d4a39 elementor-widget elementor-widget-off-canvas\" data-id=\"d3d4a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;entrance_animation&quot;:&quot;slideInLeft&quot;,&quot;exit_animation&quot;:&quot;slideInLeft&quot;,&quot;prevent_scroll&quot;:&quot;yes&quot;}\" data-widget_type=\"off-canvas.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"off-canvas-d3d4a39\" class=\"e-off-canvas\" role=\"dialog\" aria-hidden=\"true\" aria-label=\"Off-Canvas\" aria-modal=\"true\" inert=\"\" data-delay-child-handlers=\"true\">\n\t\t\t<div class=\"e-off-canvas__overlay\"><\/div>\n\t\t\t<div class=\"e-off-canvas__main\">\n\t\t\t\t<div class=\"e-off-canvas__content\">\n\t\t\t\t\t<div class=\"elementor-element elementor-element-b28c249 e-con-full e-flex e-con e-child\" data-id=\"b28c249\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-090d7c3 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"090d7c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/de\/\">\n\t\t\t<img decoding=\"async\" width=\"312\" height=\"87\" src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png\" class=\"attachment-full size-full wp-image-3071\" alt=\"\" srcset=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png 312w, https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent-300x84.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" title=\"\">\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5721f0b elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"5721f0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-5721f0b\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-3426\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/\" title=\"home\" class=\"elementor-item\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3427\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/hotels\/\" class=\"elementor-item\">Hotels<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3428\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/golf-kurse\" class=\"elementor-item\">Golfkurse<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3429\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/greenfees-de\/\" class=\"elementor-item\">Greenfees<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3874\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/besondere-angebote\/\" title=\"special offers\" class=\"elementor-item\">Besondere Angebote<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3431\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/\" class=\"elementor-item\">Dienstleistungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3432\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/#autovermietung\" class=\"elementor-item elementor-item-anchor\">Autovermietung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3433\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/#flughafen-transfers\" class=\"elementor-item elementor-item-anchor\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3434\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/schnelle-anfrage\/\" class=\"elementor-item\">Schnelle Anfrage<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-28 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-28-en\"><a href=\"https:\/\/mallorcagolfholidays.com\/\" title=\"Wechseln zu Englisch\" aria-label=\"Wechseln zu Englisch\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Englisch\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-28 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-28-es\"><a href=\"https:\/\/mallorcagolfholidays.com\/es\/\" title=\"Wechseln zu Spanisch\" aria-label=\"Wechseln zu Spanisch\" class=\"elementor-item\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"Spanisch\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5721f0b\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-3426\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/\" title=\"home\" class=\"elementor-item\" tabindex=\"-1\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3427\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/hotels\/\" class=\"elementor-item\" tabindex=\"-1\">Hotels<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3428\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/golf-kurse\" class=\"elementor-item\" tabindex=\"-1\">Golfkurse<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3429\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/greenfees-de\/\" class=\"elementor-item\" tabindex=\"-1\">Greenfees<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3874\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/besondere-angebote\/\" title=\"special offers\" class=\"elementor-item\" tabindex=\"-1\">Besondere Angebote<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3431\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/\" class=\"elementor-item\" tabindex=\"-1\">Dienstleistungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3432\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/#autovermietung\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Autovermietung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3433\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/dienstleistungen\/#flughafen-transfers\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Transfers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3434\"><a href=\"https:\/\/mallorcagolfholidays.com\/de\/schnelle-anfrage\/\" class=\"elementor-item\" tabindex=\"-1\">Schnelle Anfrage<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-28 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-28-en\"><a href=\"https:\/\/mallorcagolfholidays.com\/\" title=\"Wechseln zu Englisch\" aria-label=\"Wechseln zu Englisch\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Englisch\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-28 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-28-es\"><a href=\"https:\/\/mallorcagolfholidays.com\/es\/\" title=\"Wechseln zu Spanisch\" aria-label=\"Wechseln zu Spanisch\" class=\"elementor-item\" tabindex=\"-1\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"Spanisch\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a00a242 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"a00a242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color-300x133.webp\" class=\"attachment-medium size-medium wp-image-3088\" alt=\"\" srcset=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color-300x133.webp 300w, https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color.webp 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/header>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d657bf e-flex e-con-boxed e-con e-parent\" data-id=\"6d657bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f2852b elementor-widget elementor-widget-heading\" data-id=\"9f2852b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DSVGO<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96d99ed e-flex e-con-boxed e-con e-parent\" data-id=\"96d99ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40f23c8 elementor-widget elementor-widget-text-editor\" data-id=\"40f23c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>DSVGO<\/strong><br>In dieser Datenschutzrichtlinie informieren wir Sie \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten.<\/p>\n<p><strong>SERVER LOG FILES<\/strong><br>Zur \u00dcberwachung der technischen Funktion und zur Erh\u00f6hung der Betriebssicherheit unseres Webhosts werden Verbindungsdaten verarbeitet<br>. Die Dauer der Verarbeitung ist auf 30 Tage begrenzt.<\/p>\n<p>Rechtsgrundlage f\u00fcr die Datenverarbeitung ist das berechtigte Interesse (unbedingte technische Notwendigkeit einer Server-Logdatei als Basisdatenbank f\u00fcr die Fehleranalyse und f\u00fcr Sicherheitsma\u00dfnahmen im Rahmen des von Ihnen ausdr\u00fccklich angeforderten Dienstes<br>&#8222;Website&#8220;) gem\u00e4\u00df Art. 6 Abs. 1 lit. f&nbsp;DSVGO.<\/p>\n<p><strong>KONTAKTFORMULAR<\/strong><br>Sie k\u00f6nnen uns direkt \u00fcber ein Kontaktformular auf unserer Website kontaktieren. Nach Absenden des Kontaktformulars werden die von Ihnen eingegebenen personenbezogenen Daten von dem f\u00fcr die Verarbeitung Verantwortlichen zum Zwecke der Bearbeitung Ihrer Anfrage auf Grundlage der von Ihnen durch Absenden des Formulars erteilten Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 lit. f DSVGO. Art. 6 Abs. 1 lit. a DSVGO bis auf Widerruf.<br>Es besteht keine gesetzliche oder vertragliche Verpflichtung zur Bereitstellung personenbezogener Daten. Es besteht keine gesetzliche oder vertragliche Verpflichtung zur Bereitstellung personenbezogener Daten.<\/p>\n<p><strong>WEB-FONTS<\/strong><br>Diese Website verwendet Google Web Fonts, diese sind lokal auf unserem Server gespeichert, es werden diesbez\u00fcglich keine Daten an den Google-Server gesendet oder empfangen.<\/p>\n<p><b>INFORMATIONEN \u00dcBER DIE VERWENDUNG VON COOKIES<\/b><br>Mallorca Golf Connection S.L. verwendet teilweise sogenannte Cookies. Cookies richten auf Ihrem Computer keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen.<\/p>\n<p>Was sind Cookies?<\/p>\n<p>Internet-Cookies sind kleine Textdateien, die auf Ihrem Computer gespeichert sind und von Ihrem Browser gespeichert werden. Diese k\u00f6nnen vom Webserver jedes Mal verwendet werden, wenn Sie die Website besuchen.<\/p>\n<p>Der Betreiber der Website bestimmt, welche Art von Informationen ein Cookie enth\u00e4lt und welchen Zweck es erf\u00fcllt. Cookies werden verwendet, um Zeit zu sparen und das Surfen im Internet effizienter zu gestalten. Cookies k\u00f6nnen jedoch f\u00fcr verschiedene Zwecke verwendet werden.<\/p>\n<p>Es gibt eine gro\u00dfe Anzahl von Leitf\u00e4den, die erkl\u00e4ren, was Cookies sind und wof\u00fcr sie verwendet werden. Wir erkl\u00e4ren, welche Cookies die Website von Mallorca Golf Connection S.L. verwendet.<\/p>\n<p>Mallorca Golf Connection S.L. verwendet nur die Cookies, zu deren Verwendung Sie uns erm\u00e4chtigen. Sie k\u00f6nnen Ihre Cookies \u00fcber Ihren Browser kontrollieren. Im Folgenden beschreiben wir einige verschiedene Gruppen von Cookies, die wir verwenden:<\/p>\n<p>1. Performance-Cookies<\/p>\n<p>2. funktionale Cookies<\/p>\n<p>3. Marketing-Kekse<\/p>\n<p>Weitere Informationen \u00fcber diese Arten von Cookies finden Sie unten.<\/p>\n<p>1. Performance Cookies<\/p>\n<p>Dies sind Cookies, die Informationen dar\u00fcber sammeln, wie Sie die Website nutzen (z.B. die Seiten, die Sie besuchen oder wenn ein Fehler auftritt) oder die Mallorca Golf Connection S.L. zur Fehlerbehebung auf der Website verwendet. Alle gesammelten Informationen sind v\u00f6llig anonym und helfen uns zu verstehen, wie unsere Website funktioniert, um notwendige Verbesserungen vorzunehmen und Ihnen die Navigation zu erleichtern.<\/p>\n<p>Diese Cookies erm\u00f6glichen:<\/p>\n<p>Dass Sie unsere Website besuchen k\u00f6nnen&#8230;<\/p>\n<p>Mallorca Golf Connection S.L., um Informationen dar\u00fcber zu sammeln, wie Sie die Website nutzen, um die Benutzerfreundlichkeit der Website zu verstehen und uns zu helfen, die notwendigen Verbesserungen umzusetzen. Diese Cookies sammeln keine Informationen \u00fcber Sie, die zu Werbezwecken verwendet werden k\u00f6nnten, oder Informationen \u00fcber Ihre Pr\u00e4ferenzen (wie z.B. Ihre Benutzerdaten), die \u00fcber diesen speziellen Besuch hinausgehen.<\/p>\n<p>2. funktionale Cookies<\/p>\n<p>Wir verwenden diese Cookies, um die Benutzerfreundlichkeit der Website von Mallorca Golf Connection S.L. zu verbessern. Sie k\u00f6nnen die Verwendung solcher Cookies jederzeit ablehnen. Mallorca Golf Connection S.L. verwendet diese Cookies, um bestimmte Konfigurationsparameter zu speichern oder um bestimmte Dienste oder Meldungen bereitzustellen, die Ihre Erfahrung auf unserer Website verbessern k\u00f6nnen. Zum Beispiel, um Sie daran zu erinnern, welches Land oder welche Sprache Sie beim Besuch der Seiten gew\u00e4hlt haben. Diese Cookies werden nicht f\u00fcr Marketingzwecke verwendet.<\/p>\n<p>Diese Cookies erm\u00f6glichen:<\/p>\n<p>Ihre Anmeldedaten speichern, wenn Sie auf die Website zur\u00fcckkehren<\/p>\n<p>Diese Cookies sammeln keine Informationen \u00fcber Sie, die zu Werbezwecken verwendet werden k\u00f6nnten, oder Informationen \u00fcber Ihre Pr\u00e4ferenzen (wie z.B. Ihre Benutzerdaten), die \u00fcber diesen speziellen Besuch hinausgehen.<\/p>\n<p>3. Marketing Cookies<\/p>\n<p>Diese Cookies werden von Dritten verwaltet und k\u00f6nnen Tools verwenden, um die Verwendung dieser Cookies einzuschr\u00e4nken. Einige der Cookies werden verwendet, um auf andere Websites zu verlinken, die bestimmte Dienstleistungen f\u00fcr Mallorca Golf Connection S.L. anbieten, wie z.B. Facebook. Einige dieser Cookies ver\u00e4ndern die Werbung auf anderen Websites, um sie an Ihre Pr\u00e4ferenzen anzupassen.<\/p>\n<p>Diese Cookies erm\u00f6glichen:<\/p>\n<p>Verkn\u00fcpfung mit sozialen Netzwerken<\/p>\n<p>\u00dcbermittlung von Informationen \u00fcber Ihren Besuch auf der Website von Mallorca Golf Connection S.L., um die Werbung auf anderen Websites anzupassen.<\/p>\n<p>Sie k\u00f6nnen die Verwendung bestimmter Cookies auf der Website von Mallorca Golf Connection S.L. nicht nur akzeptieren oder ablehnen, sondern auch \u00fcber die Einstellungen Ihres Browsers Cookies verwalten.<\/p>\n<p>Sie k\u00f6nnen jederzeit von Ihrem Recht Gebrauch machen, Cookies von dieser Website zu deaktivieren oder zu entfernen. Diese Aktionen werden je nach verwendetem Browser unterschiedlich ausgef\u00fchrt.<\/p>\n<p>Verwenden Sie die Option &#8222;Hilfe&#8220;, um zu erfahren, wie Sie Cookies auf Ihrem PC verwalten k\u00f6nnen.<\/p>\n<p><strong>GOOGLE ANALYTICS<\/strong><br>Wenn Sie Ihre Einwilligung geben, verarbeiten wir Ihre personenbezogenen Daten mit dem Dienst Google Analytics, Google LLC, Amphitheatre Parkway, Mountain View, CA 94043, USA, als gemeinsam f\u00fcr die Verarbeitung Verantwortlichen zum Zweck der Fehleranalyse und der statistischen Auswertung unserer Website. Die Nichterteilung der Zustimmung hat keine direkten Auswirkungen auf die Funktion der Website, aber ohne statistische Daten wird es f\u00fcr uns schwieriger, die Website weiterzuentwickeln. Sie k\u00f6nnen eine bereits erteilte Einwilligung widerrufen, indem Sie die Datenschutzeinstellungen \u00e4ndern.<\/p>\n<p>Wir erm\u00f6glichen dem Dienst die Erfassung von Verbindungsdaten, Daten Ihres Webbrowsers und Daten \u00fcber den aufgerufenen Inhalt sowie die<br>Ausf\u00fchrung von Analysesoftware und die Speicherung von Daten auf Ihrem Endger\u00e4t. Der Dienst anonymisiert die erfassten Daten sofort nach der Erfassung und stellt uns die anonymen Daten in Form von Statistiken zur Analyse zur Verf\u00fcgung. Wir verwenden diese Statistiken zur Fehlersuche und zur Weiterentwicklung unserer Website. Die Daten auf Ihrem Endger\u00e4t werden f\u00fcr einen Zeitraum von bis zu zwei Jahren gespeichert.<\/p>\n<p>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist Ihre Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 lit. a GDPR. Die Google-Gruppe \u00fcbermittelt Ihre personenbezogenen Daten in die USA. Die Rechtsgrundlage f\u00fcr die \u00dcbermittlung von Daten in die USA ist Ihre Einwilligung gem\u00e4\u00df Art. 49 Abs. 1 lit a i.V.m. Art. 6 Abs. 1 lit a GDPR in Verbindung mit \u00a725 TTDSG. Sie wurden bereits vor Ihrer Einwilligung dar\u00fcber informiert, dass in den USA kein Datenschutzniveau besteht, das den Standards der EU entspricht. Insbesondere k\u00f6nnen die US-Geheimdienste auf Ihre Daten zugreifen, ohne dass Sie dar\u00fcber informiert werden und ohne dass Sie dagegen rechtlich vorgehen k\u00f6nnen. Aus diesem Grund hat der Europ\u00e4ische Gerichtshof die bisherige Angemessenheitsentscheidung (Privacy Shield) in einem Urteil f\u00fcr ung\u00fcltig erkl\u00e4rt.<\/p>\n<p><strong>RECAPTCHA<\/strong><br>Zum Schutz Ihrer Anfragen \u00fcber das Internetformular verwenden wir den reCAPTCHA-Dienst von Google Inc. (Google). Die Abfrage dient dazu, zu unterscheiden, ob die Eingabe von einem Menschen oder missbr\u00e4uchlich durch automatisierte, maschinelle Verarbeitung erfolgt. Die Abfrage beinhaltet die \u00dcbermittlung der IP-Adresse und anderer Daten, die von Google f\u00fcr den reCAPTCHA-Dienst ben\u00f6tigt werden, an Google. Zu diesem Zweck wird Ihre Eingabe an Google \u00fcbermittelt und dort verwendet. Ihre IP-Adresse wird von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung dieses Dienstes auszuwerten. Die von Ihrem Browser im Rahmen von reCaptcha \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. F\u00fcr diese Daten gelten die abweichenden Datenschutzbestimmungen von Google. Weitere Informationen zu den Datenschutzbestimmungen von Google finden Sie hier.<\/p>\n<p><strong>GOOGLE MAPS<\/strong><br>Google Maps ist ein Online-Kartendienst, der von Google Inc. Mit Google Maps k\u00f6nnen Sie \u00fcber einen PC oder eine App nach dem genauen Standort von St\u00e4dten, Sehensw\u00fcrdigkeiten, Unterk\u00fcnften oder Unternehmen im Internet suchen. Wenn Unternehmen auf Google My Business vertreten sind, werden neben dem Standort auch weitere Informationen \u00fcber das Unternehmen angezeigt. Kartenausschnitte eines Standorts k\u00f6nnen mit HTML-Code in eine Website integriert werden, um die Wegbeschreibung anzuzeigen. Google Maps zeigt die Erdoberfl\u00e4che als Stra\u00dfenkarte oder als Luft- oder Satellitenbild an. Dank der Street View-Bilder und der hochwertigen Satellitenbilder sind sehr pr\u00e4zise Visualisierungen m\u00f6glich.<\/p>\n<p>Warum verwenden wir Google Maps auf unserer Website?<\/p>\n<p>Alle unsere Bem\u00fchungen auf dieser Website zielen darauf ab, Ihnen eine n\u00fctzliche und sinnvolle Zeit auf unserer Website zu bieten. Durch die Integration von Google Maps k\u00f6nnen wir Ihnen die wichtigsten Informationen \u00fcber verschiedene Standorte zur Verf\u00fcgung stellen. Dank Google Maps k\u00f6nnen Sie auf einen Blick sehen, wo wir uns befinden. Die Wegbeschreibung zeigt Ihnen immer den besten oder schnellsten Weg zu uns. Sie k\u00f6nnen die Wegbeschreibung f\u00fcr Routen mit dem Auto, den \u00f6ffentlichen Verkehrsmitteln, zu Fu\u00df oder mit dem Fahrrad abrufen. F\u00fcr uns ist die Bereitstellung von Google Maps ein Teil unseres Kundenservice.<\/p>\n<p>Welche Daten werden von Google Maps gespeichert?<\/p>\n<p>Damit Google Maps seinen vollen Service anbieten kann, muss das Unternehmen Daten von Ihnen sammeln und speichern. Dazu geh\u00f6ren die eingegebenen Suchbegriffe, Ihre IP-Adresse und die Koordinaten f\u00fcr L\u00e4ngen- und Breitengrad. Wenn Sie die Routenplanerfunktion verwenden, wird auch die eingegebene Startadresse gespeichert. Diese Datenspeicherung findet jedoch auf den Websites von Google Maps statt. Wir k\u00f6nnen Sie dar\u00fcber nur informieren, aber keinen Einfluss darauf nehmen. Da wir Google Maps in unsere Website integriert haben, setzt Google mindestens ein Cookie (Name: NID) in Ihrem Browser. Dieses Cookie speichert Daten \u00fcber Ihr Nutzerverhalten. Google nutzt diese Daten in erster Linie, um seine eigenen Dienste zu optimieren und Ihnen individuelle, personalisierte Werbung zukommen zu lassen.<\/p>\n<p><strong>WIDERSTANDSRECHT<\/strong><br>Wenn Ihre personenbezogenen Daten auf der Grundlage eines berechtigten Interesses verarbeitet werden, haben Sie das Recht, dieser Verarbeitung zu widersprechen.<br>, um der Verarbeitung zu widersprechen.<\/p>\n<p>Liegen keine zwingenden schutzw\u00fcrdigen Gr\u00fcnde f\u00fcr die Verarbeitung unsererseits vor, wird die Verarbeitung Ihrer Daten auf der Grundlage dieser Datenschutzerkl\u00e4rung aufgehoben.<br>Rechtsgrundlage entf\u00e4llt.<\/p>\n<p>Sie haben auch das Recht, der Verarbeitung Ihrer personenbezogenen Daten zum Zweck des Direktmarketings zu widersprechen. Wenn Sie auf widersprechen, werden Ihre personenbezogenen Daten nicht mehr f\u00fcr die Zwecke des Direktmarketings verarbeitet.<\/p>\n<p>Die Rechtm\u00e4\u00dfigkeit der vor dem Einspruch verarbeiteten Daten wird durch den Einspruch nicht ber\u00fchrt.<\/p>\n<p><strong>RECHT AUF WIDERRUF<\/strong><br>Sie haben das Recht, Ihre Einwilligung jederzeit zu widerrufen, indem Sie die Datenschutzeinstellungen \u00e4ndern.<\/p>\n<p>Wenn Sie dem Erhalt elektronischer Werbung zugestimmt haben, k\u00f6nnen Sie Ihre Zustimmung widerrufen, indem Sie auf den Link zum Abbestellen klicken. In diesem Fall wird die Verarbeitung eingestellt, es sei denn, es gibt eine andere Rechtsgrundlage.<\/p>\n<p>Die Rechtm\u00e4\u00dfigkeit der bis zum Zeitpunkt des Widerrufs verarbeiteten Daten wird durch den Widerruf nicht ber\u00fchrt.<\/p>\n<p><strong>BETROFFENE RECHTE<\/strong><br>Sie haben au\u00dferdem das Recht auf Auskunft, Berichtigung, L\u00f6schung und Einschr\u00e4nkung der Verarbeitung personenbezogener Daten.<\/p>\n<p>Wenn die Rechtsgrundlage f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Ihre Einwilligung oder ein mit Ihnen geschlossener Vertrag ist, haben Sie auch das Recht auf Daten\u00fcbertragbarkeit.<\/p>\n<p>Sie haben auch das Recht, eine Beschwerde bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde einzureichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1378d96 e-con-full e-flex e-con e-parent\" data-id=\"1378d96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c6ed24 elementor-widget elementor-widget-template\" data-id=\"9c6ed24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<footer data-elementor-type=\"footer\" data-elementor-id=\"3274\" class=\"elementor elementor-3274 elementor-620 elementor-620\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-2233343 e-con-full e-flex e-con e-parent\" data-id=\"2233343\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9932e7d e-con-full e-flex e-con e-child\" data-id=\"9932e7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f857451 e-con-full e-flex e-con e-child\" data-id=\"f857451\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0deec0c dce_masking-none elementor-widget elementor-widget-image\" data-id=\"0deec0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/de\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"312\" height=\"87\" src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png\" class=\"attachment-medium_large size-medium_large wp-image-3071\" alt=\"\" srcset=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent.png 312w, https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/logo-farbig-transparent-300x84.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4621f2d e-con-full e-flex e-con e-child\" data-id=\"4621f2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd9356d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"cd9356d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"177\" src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color.webp\" class=\"attachment-medium_large size-medium_large wp-image-3088\" alt=\"\" srcset=\"https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color.webp 400w, https:\/\/mallorcagolfholidays.com\/wp-content\/uploads\/2024\/07\/iagto-logo-color-300x133.webp 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09b6f7a e-con-full e-flex e-con e-child\" data-id=\"09b6f7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b10ce4 elementor-widget elementor-widget-text-editor\" data-id=\"5b10ce4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/de\/?page_id=3254\">Impressum<\/a> | <a href=\"https:\/\/mallorcagolfholidays.com\/de\/dsvgo\/\">DSVGO<\/a> | <a href=\"https:\/\/mallorcagolfholidays.com\/de\/agb\/\">AGB<\/a> | <a href=\"https:\/\/mallorcagolfholidays.com\/de\/?page_id=3251\">Schnelles Angebot<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0987570 elementor-widget elementor-widget-shortcode\" data-id=\"0987570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div role=\"navigation\" aria-label=\"Sprachwechsler\" class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/\" hreflang=\"en\" lang=\"en\" class=\"wpml-ls-link\" aria-label=\"Wechseln zu English\" title=\"Wechseln zu English\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">English<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-de wpml-ls-current-language wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/de\/\" hreflang=\"de\" lang=\"de\" class=\"wpml-ls-link\" aria-current=\"page\" aria-label=\"Wechseln zu Deutsch\" title=\"Wechseln zu Deutsch\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Deutsch<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/mallorcagolfholidays.com\/es\/\" hreflang=\"es\" lang=\"es\" class=\"wpml-ls-link\" aria-label=\"Wechseln zu Espa\u00f1ol\" title=\"Wechseln zu Espa\u00f1ol\">\n\t\t\t\t\t                                    <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/mallorcagolfholidays.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/es.svg\"\n            alt=\"\"\n            loading=\"lazy\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Espa\u00f1ol<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/footer>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DSVGO DSVGOIn dieser Datenschutzrichtlinie informieren wir Sie \u00fcber die Verarbeitung Ihrer pers\u00f6nlichen Daten. SERVER LOG FILESZur \u00dcberwachung der technischen Funktion und zur Erh\u00f6hung der Betriebssicherheit unseres Webhosts werden Verbindungsdaten verarbeitet. Die Dauer der Verarbeitung ist auf 30 Tage begrenzt. Rechtsgrundlage f\u00fcr die Datenverarbeitung ist das berechtigte Interesse (unbedingte technische Notwendigkeit einer Server-Logdatei als Basisdatenbank f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3286","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/pages\/3286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/comments?post=3286"}],"version-history":[{"count":10,"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/pages\/3286\/revisions"}],"predecessor-version":[{"id":3695,"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/pages\/3286\/revisions\/3695"}],"wp:attachment":[{"href":"https:\/\/mallorcagolfholidays.com\/de\/wp-json\/wp\/v2\/media?parent=3286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}